{"id":1632,"date":"2002-06-29T12:00:01","date_gmt":"2002-06-29T03:00:01","guid":{"rendered":"http:\/\/www.tonashika.com\/wordpress\/2002\/06\/29\/%e3%81%93%e3%81%aeraid%e3%82%ab%e3%83%bc%e3%83%89%e3%81%af%e3%82%82%e3%81%86%e6%80%96%e3%81%8f%e3%81%a6%e4%bd%bf%e3%81%88%e3%81%aa%e3%81%84%e3%83%bb%e3%83%bb%e3%83%bb\/"},"modified":"2002-06-29T12:00:01","modified_gmt":"2002-06-29T03:00:01","slug":"%e3%81%93%e3%81%aeraid%e3%82%ab%e3%83%bc%e3%83%89%e3%81%af%e3%82%82%e3%81%86%e6%80%96%e3%81%8f%e3%81%a6%e4%bd%bf%e3%81%88%e3%81%aa%e3%81%84%e3%83%bb%e3%83%bb%e3%83%bb","status":"publish","type":"post","link":"https:\/\/www.tonashika.com\/wordpress\/2002\/06\/29\/%e3%81%93%e3%81%aeraid%e3%82%ab%e3%83%bc%e3%83%89%e3%81%af%e3%82%82%e3%81%86%e6%80%96%e3%81%8f%e3%81%a6%e4%bd%bf%e3%81%88%e3%81%aa%e3%81%84%e3%83%bb%e3%83%bb%e3%83%bb\/","title":{"rendered":"\u3053\u306eRAID\u30ab\u30fc\u30c9\u306f\u3082\u3046\u6016\u304f\u3066\u4f7f\u3048\u306a\u3044\u30fb\u30fb\u30fb"},"content":{"rendered":"<p>\u4fe1\u7528\u30ac\u30bf\u843d\u3061\u3084\u306a\u3041\u3000\u541b\u30a3<br \/>\n\u3063\u3066\u306a\u611f\u3058\u3067\uff0c\u3084\u3063\u3071\u308a\u3053\u306e2480\u5186\u306eRAID\u30ab\u30fc\u30c9\u306b\u3082\u554f\u984c\u306e\u4e00\u7aef\u304c\u3042\u308b\u3088\u3046\u306a\u6c17\u304c\u3057\u306a\u3044\u3067\u3082\u306a\u3044\uff0e\u3068\u306b\u304b\u304f\uff0c\u6016\u304f\u3066\u3064\u304b\u3048\u307e\u305b\u3093\u306a\uff0e<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u4fe1\u7528\u30ac\u30bf\u843d\u3061\u3084\u306a\u3041\u3000\u541b\u30a3 \u3063\u3066\u306a\u611f\u3058\u3067\uff0c\u3084\u3063\u3071\u308a\u3053\u306e2480\u5186\u306eRAID\u30ab\u30fc\u30c9\u306b &hellip; <a href=\"https:\/\/www.tonashika.com\/wordpress\/2002\/06\/29\/%e3%81%93%e3%81%aeraid%e3%82%ab%e3%83%bc%e3%83%89%e3%81%af%e3%82%82%e3%81%86%e6%80%96%e3%81%8f%e3%81%a6%e4%bd%bf%e3%81%88%e3%81%aa%e3%81%84%e3%83%bb%e3%83%bb%e3%83%bb\/\">\u7d9a\u304d\u3092\u8aad\u3080 <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1632","post","type-post","status-publish","format-standard","hentry","category-1"],"_links":{"self":[{"href":"https:\/\/www.tonashika.com\/wordpress\/wp-json\/wp\/v2\/posts\/1632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tonashika.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tonashika.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tonashika.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tonashika.com\/wordpress\/wp-json\/wp\/v2\/comments?post=1632"}],"version-history":[{"count":0,"href":"https:\/\/www.tonashika.com\/wordpress\/wp-json\/wp\/v2\/posts\/1632\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tonashika.com\/wordpress\/wp-json\/wp\/v2\/media?parent=1632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tonashika.com\/wordpress\/wp-json\/wp\/v2\/categories?post=1632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tonashika.com\/wordpress\/wp-json\/wp\/v2\/tags?post=1632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}